{"id":1204,"date":"2026-04-28T15:04:09","date_gmt":"2026-04-28T15:04:09","guid":{"rendered":"https:\/\/agriboss.hovenieronline.be\/product\/gtm-professional-1800wd-honda-fr\/"},"modified":"2026-06-15T12:35:33","modified_gmt":"2026-06-15T12:35:33","slug":"gtm-professional-1800wd-honda-fr","status":"publish","type":"product","link":"https:\/\/agriboss.hovenieronline.be\/fr\/produit\/gtm-professional-1800wd-honda-fr\/","title":{"rendered":"1800WD Honda"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":1205,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[132,126],"product_tag":[143,100],"class_list":{"0":"post-1204","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-broyeurs-gtm-fr","7":"product_cat-gtm-professionnel-fr","8":"product_tag-gtm-professional","9":"product_tag-syndified","11":"first","12":"instock","13":"shipping-taxable","14":"purchasable","15":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>GTM Professional 1800WD Honda<\/title>\n<meta name=\"description\" content=\"GTM Professional 1800WD Honda Le broyeur de branches automoteur 1800WD est con\u00e7u pour les professionnels de l&#039;entretien des arbres et des jardins. Gr...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/agriboss.hovenieronline.be\/fr\/produit\/gtm-professional-1800wd-honda-fr\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"GTM Professional 1800WD Honda\" \/>\n<meta property=\"og:description\" content=\"GTM Professional 1800WD Honda Le broyeur de branches automoteur 1800WD est con\u00e7u pour les professionnels de l&#039;entretien des arbres et des jardins. Gr...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/agriboss.hovenieronline.be\/fr\/produit\/gtm-professional-1800wd-honda-fr\/\" \/>\n<meta property=\"og:site_name\" content=\"Agri-Boss\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-15T12:35:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/agriboss.hovenieronline.be\/wp-content\/uploads\/2026\/06\/1800WDHonda-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"GTM Professional 1800WD Honda\" \/>\n<meta name=\"twitter:description\" content=\"GTM Professional 1800WD Honda Le broyeur de branches automoteur 1800WD est con\u00e7u pour les professionnels de l&#039;entretien des arbres et des jardins. Gr...\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/agriboss.hovenieronline.be\/wp-content\/uploads\/2026\/06\/1800WDHonda-1.jpeg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/agriboss.hovenieronline.be\\\/fr\\\/produit\\\/gtm-professional-1800wd-honda-fr\\\/\",\"url\":\"https:\\\/\\\/agriboss.hovenieronline.be\\\/fr\\\/produit\\\/gtm-professional-1800wd-honda-fr\\\/\",\"name\":\"GTM Professional 1800WD Honda\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agriboss.hovenieronline.be\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/agriboss.hovenieronline.be\\\/fr\\\/produit\\\/gtm-professional-1800wd-honda-fr\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/agriboss.hovenieronline.be\\\/fr\\\/produit\\\/gtm-professional-1800wd-honda-fr\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/agriboss.hovenieronline.be\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/1800WDHonda-1.jpeg\",\"datePublished\":\"2026-04-28T15:04:09+00:00\",\"dateModified\":\"2026-06-15T12:35:33+00:00\",\"description\":\"GTM Professional 1800WD Honda Le broyeur de branches automoteur 1800WD est con\u00e7u pour les professionnels de l'entretien des arbres et des jardins. Gr...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/agriboss.hovenieronline.be\\\/fr\\\/produit\\\/gtm-professional-1800wd-honda-fr\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/agriboss.hovenieronline.be\\\/fr\\\/produit\\\/gtm-professional-1800wd-honda-fr\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/agriboss.hovenieronline.be\\\/fr\\\/produit\\\/gtm-professional-1800wd-honda-fr\\\/#primaryimage\",\"url\":\"https:\\\/\\\/agriboss.hovenieronline.be\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/1800WDHonda-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/agriboss.hovenieronline.be\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/1800WDHonda-1.jpeg\",\"width\":900,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/agriboss.hovenieronline.be\\\/fr\\\/produit\\\/gtm-professional-1800wd-honda-fr\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/agriboss.hovenieronline.be\\\/fr\\\/home-2\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Boutique\",\"item\":\"https:\\\/\\\/agriboss.hovenieronline.be\\\/fr\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"1800WD Honda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/agriboss.hovenieronline.be\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/agriboss.hovenieronline.be\\\/fr\\\/\",\"name\":\"Agri-Boss\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/agriboss.hovenieronline.be\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"GTM Professional 1800WD Honda","description":"GTM Professional 1800WD Honda Le broyeur de branches automoteur 1800WD est con\u00e7u pour les professionnels de l'entretien des arbres et des jardins. Gr...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/agriboss.hovenieronline.be\/fr\/produit\/gtm-professional-1800wd-honda-fr\/","og_locale":"fr_FR","og_type":"article","og_title":"GTM Professional 1800WD Honda","og_description":"GTM Professional 1800WD Honda Le broyeur de branches automoteur 1800WD est con\u00e7u pour les professionnels de l'entretien des arbres et des jardins. Gr...","og_url":"https:\/\/agriboss.hovenieronline.be\/fr\/produit\/gtm-professional-1800wd-honda-fr\/","og_site_name":"Agri-Boss","article_modified_time":"2026-06-15T12:35:33+00:00","og_image":[{"width":900,"height":900,"url":"https:\/\/agriboss.hovenieronline.be\/wp-content\/uploads\/2026\/06\/1800WDHonda-1.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"GTM Professional 1800WD Honda","twitter_description":"GTM Professional 1800WD Honda Le broyeur de branches automoteur 1800WD est con\u00e7u pour les professionnels de l'entretien des arbres et des jardins. Gr...","twitter_image":"https:\/\/agriboss.hovenieronline.be\/wp-content\/uploads\/2026\/06\/1800WDHonda-1.jpeg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/agriboss.hovenieronline.be\/fr\/produit\/gtm-professional-1800wd-honda-fr\/","url":"https:\/\/agriboss.hovenieronline.be\/fr\/produit\/gtm-professional-1800wd-honda-fr\/","name":"GTM Professional 1800WD Honda","isPartOf":{"@id":"https:\/\/agriboss.hovenieronline.be\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/agriboss.hovenieronline.be\/fr\/produit\/gtm-professional-1800wd-honda-fr\/#primaryimage"},"image":{"@id":"https:\/\/agriboss.hovenieronline.be\/fr\/produit\/gtm-professional-1800wd-honda-fr\/#primaryimage"},"thumbnailUrl":"https:\/\/agriboss.hovenieronline.be\/wp-content\/uploads\/2026\/06\/1800WDHonda-1.jpeg","datePublished":"2026-04-28T15:04:09+00:00","dateModified":"2026-06-15T12:35:33+00:00","description":"GTM Professional 1800WD Honda Le broyeur de branches automoteur 1800WD est con\u00e7u pour les professionnels de l'entretien des arbres et des jardins. Gr...","breadcrumb":{"@id":"https:\/\/agriboss.hovenieronline.be\/fr\/produit\/gtm-professional-1800wd-honda-fr\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/agriboss.hovenieronline.be\/fr\/produit\/gtm-professional-1800wd-honda-fr\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/agriboss.hovenieronline.be\/fr\/produit\/gtm-professional-1800wd-honda-fr\/#primaryimage","url":"https:\/\/agriboss.hovenieronline.be\/wp-content\/uploads\/2026\/06\/1800WDHonda-1.jpeg","contentUrl":"https:\/\/agriboss.hovenieronline.be\/wp-content\/uploads\/2026\/06\/1800WDHonda-1.jpeg","width":900,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/agriboss.hovenieronline.be\/fr\/produit\/gtm-professional-1800wd-honda-fr\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/agriboss.hovenieronline.be\/fr\/home-2\/"},{"@type":"ListItem","position":2,"name":"Boutique","item":"https:\/\/agriboss.hovenieronline.be\/fr\/boutique\/"},{"@type":"ListItem","position":3,"name":"1800WD Honda"}]},{"@type":"WebSite","@id":"https:\/\/agriboss.hovenieronline.be\/fr\/#website","url":"https:\/\/agriboss.hovenieronline.be\/fr\/","name":"Agri-Boss","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/agriboss.hovenieronline.be\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/agriboss.hovenieronline.be\/fr\/wp-json\/wp\/v2\/product\/1204","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agriboss.hovenieronline.be\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/agriboss.hovenieronline.be\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/agriboss.hovenieronline.be\/fr\/wp-json\/wp\/v2\/comments?post=1204"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agriboss.hovenieronline.be\/fr\/wp-json\/wp\/v2\/media\/1205"}],"wp:attachment":[{"href":"https:\/\/agriboss.hovenieronline.be\/fr\/wp-json\/wp\/v2\/media?parent=1204"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/agriboss.hovenieronline.be\/fr\/wp-json\/wp\/v2\/product_brand?post=1204"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/agriboss.hovenieronline.be\/fr\/wp-json\/wp\/v2\/product_cat?post=1204"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/agriboss.hovenieronline.be\/fr\/wp-json\/wp\/v2\/product_tag?post=1204"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}